{"id":34727,"date":"2025-03-15T17:56:42","date_gmt":"2025-03-15T17:56:42","guid":{"rendered":"https:\/\/euromotion.lu\/couronne-dorientation\/"},"modified":"2026-04-16T13:23:54","modified_gmt":"2026-04-16T13:23:54","slug":"couronne-dorientation","status":"publish","type":"page","link":"https:\/\/euromotion.lu\/fr\/produits\/couronne-dorientation\/","title":{"rendered":"Couronne d&rsquo;orientation"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"34727\" class=\"elementor elementor-34727 elementor-29479\">\n\t\t\t\t\r\n\t\t<div class=\"default no-position show_shadow rs-sticky-default elementor-element elementor-element-c25e39c e-flex e-con-boxed e-con e-parent\" data-id=\"c25e39c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\r\n\t\t<div class=\"default no-position show_shadow rs-sticky-default elementor-element elementor-element-fdc2cc0 e-con-full e-flex e-con e-child\" data-id=\"fdc2cc0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\r\n\t\t\t\t<div class=\"elementor-element elementor-element-00c4af9 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"00c4af9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 48c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m140.204 130.267l-22.536-22.718c-4.667-4.705-12.265-4.736-16.97-.068L215.346 303.697l-59.792-60.277c-4.667-4.705-12.265-4.736-16.97-.069l-22.719 22.536c-4.705 4.667-4.736 12.265-.068 16.971l90.781 91.516c4.667 4.705 12.265 4.736 16.97.068l172.589-171.204c4.704-4.668 4.734-12.266.067-16.971z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Couronne d'orientation \u00e0 billes<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 48c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m140.204 130.267l-22.536-22.718c-4.667-4.705-12.265-4.736-16.97-.068L215.346 303.697l-59.792-60.277c-4.667-4.705-12.265-4.736-16.97-.069l-22.719 22.536c-4.705 4.667-4.736 12.265-.068 16.971l90.781 91.516c4.667 4.705 12.265 4.736 16.97.068l172.589-171.204c4.704-4.668 4.734-12.266.067-16.971z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Couronne d'orientation \u00e0 rouleaux<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 48c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m140.204 130.267l-22.536-22.718c-4.667-4.705-12.265-4.736-16.97-.068L215.346 303.697l-59.792-60.277c-4.667-4.705-12.265-4.736-16.97-.069l-22.719 22.536c-4.705 4.667-4.736 12.265-.068 16.971l90.781 91.516c4.667 4.705 12.265 4.736 16.97.068l172.589-171.204c4.704-4.668 4.734-12.266.067-16.971z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Couronne d'orientation \u00e0 rouleaux crois\u00e9s<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 48c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m140.204 130.267l-22.536-22.718c-4.667-4.705-12.265-4.736-16.97-.068L215.346 303.697l-59.792-60.277c-4.667-4.705-12.265-4.736-16.97-.069l-22.719 22.536c-4.705 4.667-4.736 12.265-.068 16.971l90.781 91.516c4.667 4.705 12.265 4.736 16.97.068l172.589-171.204c4.704-4.668 4.734-12.266.067-16.971z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Couronne d'orientation \u00e0 engrenage externe<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 48c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m140.204 130.267l-22.536-22.718c-4.667-4.705-12.265-4.736-16.97-.068L215.346 303.697l-59.792-60.277c-4.667-4.705-12.265-4.736-16.97-.069l-22.719 22.536c-4.705 4.667-4.736 12.265-.068 16.971l90.781 91.516c4.667 4.705 12.265 4.736 16.97.068l172.589-171.204c4.704-4.668 4.734-12.266.067-16.971z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Couronne d'orientation \u00e0 engrenage interne<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 48c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m140.204 130.267l-22.536-22.718c-4.667-4.705-12.265-4.736-16.97-.068L215.346 303.697l-59.792-60.277c-4.667-4.705-12.265-4.736-16.97-.069l-22.719 22.536c-4.705 4.667-4.736 12.265-.068 16.971l90.781 91.516c4.667 4.705 12.265 4.736 16.97.068l172.589-171.204c4.704-4.668 4.734-12.266.067-16.971z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Couronne d'orientation sans engrenage<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\r\n\t\t\t\t<div class=\"elementor-element elementor-element-9141b29 elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"9141b29\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;3&quot;,&quot;navigation&quot;:&quot;dots&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;image_spacing_custom_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/euromotion.lu\/wp-content\/uploads\/2025\/04\/corona1.webp\" alt=\"corona1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 sur 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/euromotion.lu\/wp-content\/uploads\/2025\/04\/corona2-e1743486086153.webp\" alt=\"corona2\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 sur 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/euromotion.lu\/wp-content\/uploads\/2025\/04\/corona3.webp\" alt=\"corona3\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 sur 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/euromotion.lu\/wp-content\/uploads\/2026\/03\/corona5.jpg\" alt=\"corona5\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 sur 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/euromotion.lu\/wp-content\/uploads\/2026\/03\/Franke_001.png\" alt=\"Franke_001\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 sur 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/euromotion.lu\/wp-content\/uploads\/2026\/03\/Coronas.png\" alt=\"Coronas\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 sur 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/euromotion.lu\/wp-content\/uploads\/2026\/03\/ISB-CO001.png\" alt=\"ISB CO001\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 sur 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/euromotion.lu\/wp-content\/uploads\/2026\/03\/ISB-CO002.png\" alt=\"ISB CO002\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 sur 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/euromotion.lu\/wp-content\/uploads\/2026\/03\/ISB-Corona.png\" alt=\"ISB Corona\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\r\n\t\t<div class=\"default no-position show_shadow rs-sticky-default elementor-element elementor-element-5945347 e-con-full e-flex e-con e-child\" data-id=\"5945347\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\r\n\t\t<div class=\"default no-position show_shadow rs-sticky-default elementor-element elementor-element-bfb0102 e-con-full e-flex e-con e-child\" data-id=\"bfb0102\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\r\n\t\t\t\t<div class=\"elementor-element elementor-element-7502b89 elementor-widget elementor-widget-heading\" data-id=\"7502b89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Nos Produits<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\r\n\t\t\t\t<div class=\"elementor-element elementor-element-cfcbe99 hfe-submenu-icon-hide_default hfe-nav-menu__breakpoint-none hfe-link-redirect-child elementor-widget elementor-widget-navigation-menu\" data-id=\"cfcbe99\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;padding_horizontal_menu_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;16&quot;,&quot;right&quot;:&quot;20&quot;,&quot;bottom&quot;:&quot;16&quot;,&quot;left&quot;:&quot;20&quot;,&quot;isLinked&quot;:false},&quot;main_menu_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;2&quot;,&quot;right&quot;:&quot;2&quot;,&quot;bottom&quot;:&quot;2&quot;,&quot;left&quot;:&quot;2&quot;,&quot;isLinked&quot;:true},&quot;location_area_padding&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;location_area_padding_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;location_area_padding_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;location_area_padding_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;padding_horizontal_menu_item_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;padding_horizontal_menu_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;padding_horizontal_menu_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;menu_bottom_space_last_zero&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_bottom_space_last_zero_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_bottom_space_last_zero_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_bottom_space_last_zero_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;main_menu_border_radius_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;main_menu_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;main_menu_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;main_menu_hover_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;main_menu_hover_border_radius_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;main_menu_hover_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;main_menu_hover_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;dropdown_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;dropdown_border_radius_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;dropdown_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;dropdown_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;padding_horizontal_dropdown_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_horizontal_dropdown_item_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_horizontal_dropdown_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_horizontal_dropdown_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_dropdown_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;padding_vertical_dropdown_item_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_dropdown_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_dropdown_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;distance_from_menu&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;distance_from_menu_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;distance_from_menu_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;distance_from_menu_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_size&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_size_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_size_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_size_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_width_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_radius_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"navigation-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<style>\n\t\t\t.hfe-layout-vertical .left-arrow ul .menu-item:hover a:after {\n\t\t\t\tbackground: !important;\n\t\t\t}\n\t\t\t.hfe-layout-vertical .left-arrow ul .menu-item:hover a:before {\n\t\t\t\tborder-left: 6px solid \t\t\t}\n\t\t<\/style>\n\n\t\t\t\t\t<div class=\"hfe-nav-menu hfe-layout-vertical normal hfe-nav-menu-layout mega_columns1 vertical\" data-layout=\"vertical\">\n\t\t\t\t<div class=\"hfe-nav-menu__toggle elementor-clickable\">\n\t\t\t\t\t<div class=\"hfe-nav-menu-icon\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<nav class=\"hfe-nav-menu__layout-vertical hfe-nav-menu__submenu-hide_default rs_one_columns no-separator no-arrow no-circle hide_default icon-enable\" data-toggle-icon=\"\" data-close-icon=\"\" data-full-width=\"\">\n\t\t\t\t\t<ul id=\"menu-1-cfcbe99\" class=\"hfe-nav-menu\"><li id=\"menu-item-34755\" class=\"menu-item menu-item-type-post_type menu-item-object-page parent hfe-creative-menu\"><a href=\"https:\/\/euromotion.lu\/fr\/produits\/roulements\/\" class = \"hfe-menu-item\">Roulements<em class=\"rs__menu_sp_dyc\"><i class=\"ri-arrow-right-line\"><\/i><\/em><\/a><\/li>\n<li id=\"menu-item-34756\" class=\"menu-item menu-item-type-post_type menu-item-object-page parent hfe-creative-menu\"><a href=\"https:\/\/euromotion.lu\/fr\/produits\/graisses-lubrifiantes\/\" class = \"hfe-menu-item\">Graisses Lubrifiantes<em class=\"rs__menu_sp_dyc\"><i class=\"ri-arrow-right-line\"><\/i><\/em><\/a><\/li>\n<li id=\"menu-item-34757\" class=\"menu-item menu-item-type-post_type menu-item-object-page parent hfe-creative-menu\"><a href=\"https:\/\/euromotion.lu\/fr\/produits\/paliers-de-roulement\/\" class = \"hfe-menu-item\">Paliers de roulement<em class=\"rs__menu_sp_dyc\"><i class=\"ri-arrow-right-line\"><\/i><\/em><\/a><\/li>\n<li id=\"menu-item-34758\" class=\"menu-item menu-item-type-post_type menu-item-object-page parent hfe-creative-menu\"><a href=\"https:\/\/euromotion.lu\/fr\/produits\/systemes-et-composants-de-mouvement-lineaire\/\" class = \"hfe-menu-item\">Syst\u00e8mes et composants de mouvement lin\u00e9aire<em class=\"rs__menu_sp_dyc\"><i class=\"ri-arrow-right-line\"><\/i><\/em><\/a><\/li>\n<li id=\"menu-item-34759\" class=\"menu-item menu-item-type-post_type menu-item-object-page parent hfe-creative-menu\"><a href=\"https:\/\/euromotion.lu\/fr\/produits\/composants-de-transmission-de-puissance-mecanique\/\" class = \"hfe-menu-item\">Composants de Transmission de Puissance M\u00e9canique<em class=\"rs__menu_sp_dyc\"><i class=\"ri-arrow-right-line\"><\/i><\/em><\/a><\/li>\n<li id=\"menu-item-34760\" class=\"menu-item menu-item-type-post_type menu-item-object-page parent hfe-creative-menu\"><a href=\"https:\/\/euromotion.lu\/fr\/produits\/couronne-dorientation\/\" class = \"hfe-menu-item\">Couronne d&rsquo;orientation<em class=\"rs__menu_sp_dyc\"><i class=\"ri-arrow-right-line\"><\/i><\/em><\/a><\/li>\n<\/ul>\t\t\t\t<\/nav>              \n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\r\n\t\t<div class=\"default no-position show_shadow rs-sticky-default elementor-element elementor-element-9ae3d46 e-con-full e-flex e-con e-child\" data-id=\"9ae3d46\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\r\n\t\t\t\t<div class=\"elementor-element elementor-element-edea32d elementor-widget elementor-widget-rs-heading\" data-id=\"edea32d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"prelements-heading default  \">\n\t\t\t<div class=\"title-inner\">\n\t\t\t\t<h3 class=\"title rs-split-text-disable \">Vous avez un<br>projet en<br>t\u00eate ?<\/h3>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\r\n\t\t\t\t<div class=\"elementor-element elementor-element-2a826f7 elementor-widget elementor-widget-rs-button\" data-id=\"2a826f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"rs-button style1\">\r\n\t\t\t\t\t\t<a class=\"rs-btn\" href=\"https:\/\/euromotion.lu\/fr\/contact-2\/\" >\t\r\n\t\t\t\t<span>Contactez-nous \r\n\t\t\t\t\t\t\t\t\t<em>\r\n\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"12\" viewBox=\"0 0 18 12\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M0 6C0 5.66249 0.273604 5.38889 0.611111 5.38889L15.0246 5.38889L11.179 1.54323C10.9403 1.30458 10.9403 0.917644 11.179 0.67899C11.4176 0.440336 11.8046 0.440336 12.0432 0.67899L16.9321 5.56788C17.1708 5.80653 17.1708 6.19347 16.9321 6.43212L12.0432 11.321C11.8046 11.5597 11.4176 11.5597 11.179 11.321C10.9403 11.0824 10.9403 10.6954 11.179 10.4568L15.0246 6.61111L0.611111 6.61111C0.273604 6.61111 0 6.33751 0 6Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"12\" viewBox=\"0 0 18 12\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M0 6C0 5.66249 0.273604 5.38889 0.611111 5.38889L15.0246 5.38889L11.179 1.54323C10.9403 1.30458 10.9403 0.917644 11.179 0.67899C11.4176 0.440336 11.8046 0.440336 12.0432 0.67899L16.9321 5.56788C17.1708 5.80653 17.1708 6.19347 16.9321 6.43212L12.0432 11.321C11.8046 11.5597 11.4176 11.5597 11.179 11.321C10.9403 11.0824 10.9403 10.6954 11.179 10.4568L15.0246 6.61111L0.611111 6.61111C0.273604 6.61111 0 6.33751 0 6Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t\t<\/em>\t\r\n\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t<\/a>\r\n\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Couronne d&rsquo;orientation \u00e0 billes Couronne d&rsquo;orientation \u00e0 rouleaux Couronne d&rsquo;orientation \u00e0 rouleaux crois\u00e9s Couronne d&rsquo;orientation \u00e0 engrenage externe Couronne d&rsquo;orientation \u00e0 engrenage interne Couronne d&rsquo;orientation sans engrenage Nos Produits Bearings Lubricating Grease Bearing Housings Linear Motion Systems and Components Power Transmission Components Slewing Rings Vous avez unprojet ent\u00eate ? Contactez-nous<\/p>\n","protected":false},"author":1,"featured_media":29909,"parent":34739,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-34727","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Couronnes d&#039;orientation et roulements de grand diam\u00e8tre | Euromotion<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez nos couronnes d&#039;orientation haute performance et nos roulements de grand diam\u00e8tre, con\u00e7us pour les grues, les engins de chantier et les applications industrielles exigeantes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/euromotion.lu\/fr\/produits\/couronne-dorientation\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Couronnes d&#039;orientation et roulements de grand diam\u00e8tre | Euromotion\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez nos couronnes d&#039;orientation haute performance et nos roulements de grand diam\u00e8tre, con\u00e7us pour les grues, les engins de chantier et les applications industrielles exigeantes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/euromotion.lu\/fr\/produits\/couronne-dorientation\/\" \/>\n<meta property=\"og:site_name\" content=\"EUROMOTION\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-16T13:23:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/euromotion.lu\/wp-content\/uploads\/2025\/04\/Franke_001.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1784\" \/>\n\t<meta property=\"og:image:height\" content=\"767\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/euromotion.lu\\\/fr\\\/produits\\\/couronne-dorientation\\\/\",\"url\":\"https:\\\/\\\/euromotion.lu\\\/fr\\\/produits\\\/couronne-dorientation\\\/\",\"name\":\"Couronnes d'orientation et roulements de grand diam\u00e8tre | Euromotion\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/euromotion.lu\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/euromotion.lu\\\/fr\\\/produits\\\/couronne-dorientation\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/euromotion.lu\\\/fr\\\/produits\\\/couronne-dorientation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/euromotion.lu\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Franke_001.png\",\"datePublished\":\"2025-03-15T17:56:42+00:00\",\"dateModified\":\"2026-04-16T13:23:54+00:00\",\"description\":\"D\u00e9couvrez nos couronnes d'orientation haute performance et nos roulements de grand diam\u00e8tre, con\u00e7us pour les grues, les engins de chantier et les applications industrielles exigeantes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/euromotion.lu\\\/fr\\\/produits\\\/couronne-dorientation\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/euromotion.lu\\\/fr\\\/produits\\\/couronne-dorientation\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/euromotion.lu\\\/fr\\\/produits\\\/couronne-dorientation\\\/#primaryimage\",\"url\":\"https:\\\/\\\/euromotion.lu\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Franke_001.png\",\"contentUrl\":\"https:\\\/\\\/euromotion.lu\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Franke_001.png\",\"width\":1784,\"height\":767},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/euromotion.lu\\\/fr\\\/produits\\\/couronne-dorientation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/euromotion.lu\\\/fr\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/euromotion.lu\\\/fr\\\/produits\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Couronne d&#8217;orientation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/euromotion.lu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/euromotion.lu\\\/fr\\\/\",\"name\":\"Euromotion SARL\",\"description\":\"Industrial Motion &amp; Power Transmission Solutions\",\"publisher\":{\"@id\":\"https:\\\/\\\/euromotion.lu\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/euromotion.lu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/euromotion.lu\\\/fr\\\/#organization\",\"name\":\"Euromotion SARL\",\"url\":\"https:\\\/\\\/euromotion.lu\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/euromotion.lu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/euromotion.lu\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Euromotion-Logo.png\",\"contentUrl\":\"https:\\\/\\\/euromotion.lu\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Euromotion-Logo.png\",\"width\":1859,\"height\":365,\"caption\":\"Euromotion SARL\"},\"image\":{\"@id\":\"https:\\\/\\\/euromotion.lu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Couronnes d'orientation et roulements de grand diam\u00e8tre | Euromotion","description":"D\u00e9couvrez nos couronnes d'orientation haute performance et nos roulements de grand diam\u00e8tre, con\u00e7us pour les grues, les engins de chantier et les applications industrielles exigeantes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/euromotion.lu\/fr\/produits\/couronne-dorientation\/","og_locale":"fr_FR","og_type":"article","og_title":"Couronnes d'orientation et roulements de grand diam\u00e8tre | Euromotion","og_description":"D\u00e9couvrez nos couronnes d'orientation haute performance et nos roulements de grand diam\u00e8tre, con\u00e7us pour les grues, les engins de chantier et les applications industrielles exigeantes.","og_url":"https:\/\/euromotion.lu\/fr\/produits\/couronne-dorientation\/","og_site_name":"EUROMOTION","article_modified_time":"2026-04-16T13:23:54+00:00","og_image":[{"width":1784,"height":767,"url":"https:\/\/euromotion.lu\/wp-content\/uploads\/2025\/04\/Franke_001.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/euromotion.lu\/fr\/produits\/couronne-dorientation\/","url":"https:\/\/euromotion.lu\/fr\/produits\/couronne-dorientation\/","name":"Couronnes d'orientation et roulements de grand diam\u00e8tre | Euromotion","isPartOf":{"@id":"https:\/\/euromotion.lu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/euromotion.lu\/fr\/produits\/couronne-dorientation\/#primaryimage"},"image":{"@id":"https:\/\/euromotion.lu\/fr\/produits\/couronne-dorientation\/#primaryimage"},"thumbnailUrl":"https:\/\/euromotion.lu\/wp-content\/uploads\/2025\/04\/Franke_001.png","datePublished":"2025-03-15T17:56:42+00:00","dateModified":"2026-04-16T13:23:54+00:00","description":"D\u00e9couvrez nos couronnes d'orientation haute performance et nos roulements de grand diam\u00e8tre, con\u00e7us pour les grues, les engins de chantier et les applications industrielles exigeantes.","breadcrumb":{"@id":"https:\/\/euromotion.lu\/fr\/produits\/couronne-dorientation\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/euromotion.lu\/fr\/produits\/couronne-dorientation\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/euromotion.lu\/fr\/produits\/couronne-dorientation\/#primaryimage","url":"https:\/\/euromotion.lu\/wp-content\/uploads\/2025\/04\/Franke_001.png","contentUrl":"https:\/\/euromotion.lu\/wp-content\/uploads\/2025\/04\/Franke_001.png","width":1784,"height":767},{"@type":"BreadcrumbList","@id":"https:\/\/euromotion.lu\/fr\/produits\/couronne-dorientation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/euromotion.lu\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/euromotion.lu\/fr\/produits\/"},{"@type":"ListItem","position":3,"name":"Couronne d&#8217;orientation"}]},{"@type":"WebSite","@id":"https:\/\/euromotion.lu\/fr\/#website","url":"https:\/\/euromotion.lu\/fr\/","name":"Euromotion SARL","description":"Industrial Motion &amp; Power Transmission Solutions","publisher":{"@id":"https:\/\/euromotion.lu\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/euromotion.lu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/euromotion.lu\/fr\/#organization","name":"Euromotion SARL","url":"https:\/\/euromotion.lu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/euromotion.lu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/euromotion.lu\/wp-content\/uploads\/2025\/02\/Euromotion-Logo.png","contentUrl":"https:\/\/euromotion.lu\/wp-content\/uploads\/2025\/02\/Euromotion-Logo.png","width":1859,"height":365,"caption":"Euromotion SARL"},"image":{"@id":"https:\/\/euromotion.lu\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/euromotion.lu\/fr\/wp-json\/wp\/v2\/pages\/34727","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/euromotion.lu\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/euromotion.lu\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/euromotion.lu\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/euromotion.lu\/fr\/wp-json\/wp\/v2\/comments?post=34727"}],"version-history":[{"count":2,"href":"https:\/\/euromotion.lu\/fr\/wp-json\/wp\/v2\/pages\/34727\/revisions"}],"predecessor-version":[{"id":34745,"href":"https:\/\/euromotion.lu\/fr\/wp-json\/wp\/v2\/pages\/34727\/revisions\/34745"}],"up":[{"embeddable":true,"href":"https:\/\/euromotion.lu\/fr\/wp-json\/wp\/v2\/pages\/34739"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/euromotion.lu\/fr\/wp-json\/wp\/v2\/media\/29909"}],"wp:attachment":[{"href":"https:\/\/euromotion.lu\/fr\/wp-json\/wp\/v2\/media?parent=34727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}