{"id":34719,"date":"2025-03-15T17:56:24","date_gmt":"2025-03-15T17:56:24","guid":{"rendered":"https:\/\/euromotion.lu\/componentes-para-transmision-de-potencia-mecanica\/"},"modified":"2026-04-16T13:22:20","modified_gmt":"2026-04-16T13:22:20","slug":"componentes-para-transmision-de-potencia-mecanica","status":"publish","type":"page","link":"https:\/\/euromotion.lu\/es\/productos\/componentes-para-transmision-de-potencia-mecanica\/","title":{"rendered":"Componentes para Transmisi\u00f3n de Potencia Mec\u00e1nica"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"34719\" class=\"elementor elementor-34719 elementor-29477\">\n\t\t\t\t\r\n\t\t<div class=\"default no-position show_shadow rs-sticky-default elementor-element elementor-element-b117061 e-flex e-con-boxed e-con e-parent\" data-id=\"b117061\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\r\n\t\t<div class=\"default no-position show_shadow rs-sticky-default elementor-element elementor-element-b5c94ab e-con-full e-flex e-con e-child\" data-id=\"b5c94ab\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\r\n\t\t\t\t<div class=\"elementor-element elementor-element-28efc095 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"28efc095\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 48c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m140.204 130.267l-22.536-22.718c-4.667-4.705-12.265-4.736-16.97-.068L215.346 303.697l-59.792-60.277c-4.667-4.705-12.265-4.736-16.97-.069l-22.719 22.536c-4.705 4.667-4.736 12.265-.068 16.971l90.781 91.516c4.667 4.705 12.265 4.736 16.97.068l172.589-171.204c4.704-4.668 4.734-12.266.067-16.971z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Acoplamiento (cople) flexible<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 48c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m140.204 130.267l-22.536-22.718c-4.667-4.705-12.265-4.736-16.97-.068L215.346 303.697l-59.792-60.277c-4.667-4.705-12.265-4.736-16.97-.069l-22.719 22.536c-4.705 4.667-4.736 12.265-.068 16.971l90.781 91.516c4.667 4.705 12.265 4.736 16.97.068l172.589-171.204c4.704-4.668 4.734-12.266.067-16.971z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Acoplamiento (cople) r\u00edgido<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 48c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m140.204 130.267l-22.536-22.718c-4.667-4.705-12.265-4.736-16.97-.068L215.346 303.697l-59.792-60.277c-4.667-4.705-12.265-4.736-16.97-.069l-22.719 22.536c-4.705 4.667-4.736 12.265-.068 16.971l90.781 91.516c4.667 4.705 12.265 4.736 16.97.068l172.589-171.204c4.704-4.668 4.734-12.266.067-16.971z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Acoplamiento (cople) hidr\u00e1ulico<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 48c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m140.204 130.267l-22.536-22.718c-4.667-4.705-12.265-4.736-16.97-.068L215.346 303.697l-59.792-60.277c-4.667-4.705-12.265-4.736-16.97-.069l-22.719 22.536c-4.705 4.667-4.736 12.265-.068 16.971l90.781 91.516c4.667 4.705 12.265 4.736 16.97.068l172.589-171.204c4.704-4.668 4.734-12.266.067-16.971z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Acoplamiento de engranes<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 48c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m140.204 130.267l-22.536-22.718c-4.667-4.705-12.265-4.736-16.97-.068L215.346 303.697l-59.792-60.277c-4.667-4.705-12.265-4.736-16.97-.069l-22.719 22.536c-4.705 4.667-4.736 12.265-.068 16.971l90.781 91.516c4.667 4.705 12.265 4.736 16.97.068l172.589-171.204c4.704-4.668 4.734-12.266.067-16.971z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Campana de acoplamiento<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 48c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m140.204 130.267l-22.536-22.718c-4.667-4.705-12.265-4.736-16.97-.068L215.346 303.697l-59.792-60.277c-4.667-4.705-12.265-4.736-16.97-.069l-22.719 22.536c-4.705 4.667-4.736 12.265-.068 16.971l90.781 91.516c4.667 4.705 12.265 4.736 16.97.068l172.589-171.204c4.704-4.668 4.734-12.266.067-16.971z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Reductor de velocidad<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 48c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m140.204 130.267l-22.536-22.718c-4.667-4.705-12.265-4.736-16.97-.068L215.346 303.697l-59.792-60.277c-4.667-4.705-12.265-4.736-16.97-.069l-22.719 22.536c-4.705 4.667-4.736 12.265-.068 16.971l90.781 91.516c4.667 4.705 12.265 4.736 16.97.068l172.589-171.204c4.704-4.668 4.734-12.266.067-16.971z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Freno de contravuelta<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 48c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m140.204 130.267l-22.536-22.718c-4.667-4.705-12.265-4.736-16.97-.068L215.346 303.697l-59.792-60.277c-4.667-4.705-12.265-4.736-16.97-.069l-22.719 22.536c-4.705 4.667-4.736 12.265-.068 16.971l90.781 91.516c4.667 4.705 12.265 4.736 16.97.068l172.589-171.204c4.704-4.668 4.734-12.266.067-16.971z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Freno neum\u00e1tico<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 48c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m140.204 130.267l-22.536-22.718c-4.667-4.705-12.265-4.736-16.97-.068L215.346 303.697l-59.792-60.277c-4.667-4.705-12.265-4.736-16.97-.069l-22.719 22.536c-4.705 4.667-4.736 12.265-.068 16.971l90.781 91.516c4.667 4.705 12.265 4.736 16.97.068l172.589-171.204c4.704-4.668 4.734-12.266.067-16.971z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Freno hidr\u00e1ulico<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 48c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m140.204 130.267l-22.536-22.718c-4.667-4.705-12.265-4.736-16.97-.068L215.346 303.697l-59.792-60.277c-4.667-4.705-12.265-4.736-16.97-.069l-22.719 22.536c-4.705 4.667-4.736 12.265-.068 16.971l90.781 91.516c4.667 4.705 12.265 4.736 16.97.068l172.589-171.204c4.704-4.668 4.734-12.266.067-16.971z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Freno de disco electromagn\u00e9tico<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 48c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m140.204 130.267l-22.536-22.718c-4.667-4.705-12.265-4.736-16.97-.068L215.346 303.697l-59.792-60.277c-4.667-4.705-12.265-4.736-16.97-.069l-22.719 22.536c-4.705 4.667-4.736 12.265-.068 16.971l90.781 91.516c4.667 4.705 12.265 4.736 16.97.068l172.589-171.204c4.704-4.668 4.734-12.266.067-16.971z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Reductor de velocidad<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 48c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m140.204 130.267l-22.536-22.718c-4.667-4.705-12.265-4.736-16.97-.068L215.346 303.697l-59.792-60.277c-4.667-4.705-12.265-4.736-16.97-.069l-22.719 22.536c-4.705 4.667-4.736 12.265-.068 16.971l90.781 91.516c4.667 4.705 12.265 4.736 16.97.068l172.589-171.204c4.704-4.668 4.734-12.266.067-16.971z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Conjunto de retenci\u00f3n<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 48c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m140.204 130.267l-22.536-22.718c-4.667-4.705-12.265-4.736-16.97-.068L215.346 303.697l-59.792-60.277c-4.667-4.705-12.265-4.736-16.97-.069l-22.719 22.536c-4.705 4.667-4.736 12.265-.068 16.971l90.781 91.516c4.667 4.705 12.265 4.736 16.97.068l172.589-171.204c4.704-4.668 4.734-12.266.067-16.971z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Llantas libres<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 48c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m140.204 130.267l-22.536-22.718c-4.667-4.705-12.265-4.736-16.97-.068L215.346 303.697l-59.792-60.277c-4.667-4.705-12.265-4.736-16.97-.069l-22.719 22.536c-4.705 4.667-4.736 12.265-.068 16.971l90.781 91.516c4.667 4.705 12.265 4.736 16.97.068l172.589-171.204c4.704-4.668 4.734-12.266.067-16.971z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Limitadores de torque<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\r\n\t\t\t\t<div class=\"elementor-element elementor-element-048d5ba elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"048d5ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;4&quot;,&quot;navigation&quot;:&quot;dots&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;image_spacing_custom_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/euromotion.lu\/wp-content\/uploads\/2025\/04\/Clutch-2.jpg\" alt=\"Clutch 2\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/euromotion.lu\/wp-content\/uploads\/2025\/04\/Freno2.jpg\" alt=\"Freno2\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/euromotion.lu\/wp-content\/uploads\/2025\/04\/Freno1.jpg\" alt=\"Freno1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/euromotion.lu\/wp-content\/uploads\/2025\/04\/freno-neumatico.jpg\" alt=\"freno neumatico\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/euromotion.lu\/wp-content\/uploads\/2025\/04\/Cople-2.jpg\" alt=\"Cople 2\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/euromotion.lu\/wp-content\/uploads\/2025\/04\/Clutch-1.jpg\" alt=\"Clutch 1\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\r\n\t\t<div class=\"default no-position show_shadow rs-sticky-default elementor-element elementor-element-1170604 e-con-full e-flex e-con e-child\" data-id=\"1170604\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\r\n\t\t<div class=\"default no-position show_shadow rs-sticky-default elementor-element elementor-element-7657428 e-con-full e-flex e-con e-child\" data-id=\"7657428\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\r\n\t\t\t\t<div class=\"elementor-element elementor-element-2642c226 elementor-widget elementor-widget-heading\" data-id=\"2642c226\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Nuestros Productos<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\r\n\t\t\t\t<div class=\"elementor-element elementor-element-7942ba16 hfe-submenu-icon-hide_default hfe-nav-menu__breakpoint-none hfe-link-redirect-child elementor-widget elementor-widget-navigation-menu\" data-id=\"7942ba16\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;padding_horizontal_menu_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;16&quot;,&quot;right&quot;:&quot;20&quot;,&quot;bottom&quot;:&quot;16&quot;,&quot;left&quot;:&quot;20&quot;,&quot;isLinked&quot;:false},&quot;main_menu_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;2&quot;,&quot;right&quot;:&quot;2&quot;,&quot;bottom&quot;:&quot;2&quot;,&quot;left&quot;:&quot;2&quot;,&quot;isLinked&quot;:true},&quot;location_area_padding&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;location_area_padding_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;location_area_padding_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;location_area_padding_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;padding_horizontal_menu_item_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;padding_horizontal_menu_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;padding_horizontal_menu_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;menu_bottom_space_last_zero&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_bottom_space_last_zero_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_bottom_space_last_zero_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_bottom_space_last_zero_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;main_menu_border_radius_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;main_menu_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;main_menu_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;main_menu_hover_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;main_menu_hover_border_radius_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;main_menu_hover_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;main_menu_hover_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;dropdown_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;dropdown_border_radius_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;dropdown_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;dropdown_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;padding_horizontal_dropdown_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_horizontal_dropdown_item_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_horizontal_dropdown_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_horizontal_dropdown_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_dropdown_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;padding_vertical_dropdown_item_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_dropdown_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_dropdown_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;distance_from_menu&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;distance_from_menu_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;distance_from_menu_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;distance_from_menu_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_size&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_size_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_size_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_size_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_width_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_radius_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"navigation-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<style>\n\t\t\t.hfe-layout-vertical .left-arrow ul .menu-item:hover a:after {\n\t\t\t\tbackground: !important;\n\t\t\t}\n\t\t\t.hfe-layout-vertical .left-arrow ul .menu-item:hover a:before {\n\t\t\t\tborder-left: 6px solid \t\t\t}\n\t\t<\/style>\n\n\t\t\t\t\t<div class=\"hfe-nav-menu hfe-layout-vertical normal hfe-nav-menu-layout mega_columns1 vertical\" data-layout=\"vertical\">\n\t\t\t\t<div class=\"hfe-nav-menu__toggle elementor-clickable\">\n\t\t\t\t\t<div class=\"hfe-nav-menu-icon\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<nav class=\"hfe-nav-menu__layout-vertical hfe-nav-menu__submenu-hide_default rs_one_columns no-separator no-arrow no-circle hide_default icon-enable\" data-toggle-icon=\"\" data-close-icon=\"\" data-full-width=\"\">\n\t\t\t\t\t<ul id=\"menu-1-7942ba16\" class=\"hfe-nav-menu\"><li id=\"menu-item-34767\" class=\"menu-item menu-item-type-post_type menu-item-object-page parent hfe-creative-menu\"><a href=\"https:\/\/euromotion.lu\/es\/productos\/rodamientos\/\" class = \"hfe-menu-item\">Rodamientos<em class=\"rs__menu_sp_dyc\"><i class=\"ri-arrow-right-line\"><\/i><\/em><\/a><\/li>\n<li id=\"menu-item-34768\" class=\"menu-item menu-item-type-post_type menu-item-object-page parent hfe-creative-menu\"><a href=\"https:\/\/euromotion.lu\/es\/productos\/grasa-lubricante\/\" class = \"hfe-menu-item\">Grasa Lubricante<em class=\"rs__menu_sp_dyc\"><i class=\"ri-arrow-right-line\"><\/i><\/em><\/a><\/li>\n<li id=\"menu-item-34769\" class=\"menu-item menu-item-type-post_type menu-item-object-page parent hfe-creative-menu\"><a href=\"https:\/\/euromotion.lu\/es\/productos\/soportes-para-rodamiento-chumaceras\/\" class = \"hfe-menu-item\">Soportes para rodamiento (chumaceras)<em class=\"rs__menu_sp_dyc\"><i class=\"ri-arrow-right-line\"><\/i><\/em><\/a><\/li>\n<li id=\"menu-item-34770\" class=\"menu-item menu-item-type-post_type menu-item-object-page parent hfe-creative-menu\"><a href=\"https:\/\/euromotion.lu\/es\/productos\/sistemas-de-movimiento-lineal-y-componentes\/\" class = \"hfe-menu-item\">Sistemas de movimiento lineal y componentes<em class=\"rs__menu_sp_dyc\"><i class=\"ri-arrow-right-line\"><\/i><\/em><\/a><\/li>\n<li id=\"menu-item-34771\" class=\"menu-item menu-item-type-post_type menu-item-object-page parent hfe-creative-menu\"><a href=\"https:\/\/euromotion.lu\/es\/productos\/componentes-para-transmision-de-potencia-mecanica\/\" class = \"hfe-menu-item\">Componentes para Transmisi\u00f3n de Potencia Mec\u00e1nica<em class=\"rs__menu_sp_dyc\"><i class=\"ri-arrow-right-line\"><\/i><\/em><\/a><\/li>\n<li id=\"menu-item-34772\" class=\"menu-item menu-item-type-post_type menu-item-object-page parent hfe-creative-menu\"><a href=\"https:\/\/euromotion.lu\/es\/productos\/coronas-de-orientacion-coronas-giratorias\/\" class = \"hfe-menu-item\">Coronas de orientacion (coronas giratorias)<em class=\"rs__menu_sp_dyc\"><i class=\"ri-arrow-right-line\"><\/i><\/em><\/a><\/li>\n<\/ul>\t\t\t\t<\/nav>              \n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\r\n\t\t<div class=\"default no-position show_shadow rs-sticky-default elementor-element elementor-element-e904cda e-con-full e-flex e-con e-child\" data-id=\"e904cda\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\r\n\t\t\t\t<div class=\"elementor-element elementor-element-aa01693 elementor-widget elementor-widget-rs-heading\" data-id=\"aa01693\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"prelements-heading default  \">\n\t\t\t<div class=\"title-inner\">\n\t\t\t\t<h3 class=\"title rs-split-text-disable \">\u00bfTiene un proyecto en mente?<\/h3>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\r\n\t\t\t\t<div class=\"elementor-element elementor-element-2ce391d elementor-widget elementor-widget-rs-button\" data-id=\"2ce391d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"rs-button style1\">\r\n\t\t\t\t\t\t<a class=\"rs-btn\" href=\"https:\/\/euromotion.lu\/es\/contacto\/\" >\t\r\n\t\t\t\t<span>Cont\u00e1ctenos \r\n\t\t\t\t\t\t\t\t\t<em>\r\n\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"12\" viewBox=\"0 0 18 12\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M0 6C0 5.66249 0.273604 5.38889 0.611111 5.38889L15.0246 5.38889L11.179 1.54323C10.9403 1.30458 10.9403 0.917644 11.179 0.67899C11.4176 0.440336 11.8046 0.440336 12.0432 0.67899L16.9321 5.56788C17.1708 5.80653 17.1708 6.19347 16.9321 6.43212L12.0432 11.321C11.8046 11.5597 11.4176 11.5597 11.179 11.321C10.9403 11.0824 10.9403 10.6954 11.179 10.4568L15.0246 6.61111L0.611111 6.61111C0.273604 6.61111 0 6.33751 0 6Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"12\" viewBox=\"0 0 18 12\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M0 6C0 5.66249 0.273604 5.38889 0.611111 5.38889L15.0246 5.38889L11.179 1.54323C10.9403 1.30458 10.9403 0.917644 11.179 0.67899C11.4176 0.440336 11.8046 0.440336 12.0432 0.67899L16.9321 5.56788C17.1708 5.80653 17.1708 6.19347 16.9321 6.43212L12.0432 11.321C11.8046 11.5597 11.4176 11.5597 11.179 11.321C10.9403 11.0824 10.9403 10.6954 11.179 10.4568L15.0246 6.61111L0.611111 6.61111C0.273604 6.61111 0 6.33751 0 6Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t\t<\/em>\t\r\n\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t<\/a>\r\n\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\r\n\t\t<div class=\"default no-position show_shadow rs-sticky-default elementor-element elementor-element-193c327e e-flex e-con-boxed e-con e-parent\" data-id=\"193c327e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\r\n\t\t<div class=\"default no-position show_shadow rs-sticky-default elementor-element elementor-element-1d40abdd e-con-full e-flex e-con e-child\" data-id=\"1d40abdd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\r\n\t\t<div class=\"default no-position show_shadow rs-sticky-default elementor-element elementor-element-79125427 e-con-full e-flex e-con e-child\" data-id=\"79125427\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\r\n\t\t<div class=\"default no-position show_shadow rs-sticky-default elementor-element elementor-element-12af64fe e-flex e-con-boxed e-con e-child\" data-id=\"12af64fe\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\r\n\t\t<div class=\"default no-position show_shadow rs-sticky-default elementor-element elementor-element-5c7ff779 e-con-full e-flex e-con e-child\" data-id=\"5c7ff779\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\r\n\t\t\t\t<div class=\"elementor-element elementor-element-e0ad58d elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"e0ad58d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/euromotion.lu\/wp-content\/uploads\/2025\/04\/Clutch-2.jpg\" alt=\"Clutch 2\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/euromotion.lu\/wp-content\/uploads\/2025\/04\/Freno2.jpg\" alt=\"Freno2\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/euromotion.lu\/wp-content\/uploads\/2025\/04\/Freno1.jpg\" alt=\"Freno1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/euromotion.lu\/wp-content\/uploads\/2025\/04\/freno-neumatico.jpg\" alt=\"freno neumatico\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/euromotion.lu\/wp-content\/uploads\/2025\/04\/Cople-2.jpg\" alt=\"Cople 2\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/euromotion.lu\/wp-content\/uploads\/2025\/04\/Clutch-1.jpg\" alt=\"Clutch 1\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\r\n\t\t<div class=\"default no-position show_shadow rs-sticky-default elementor-element elementor-element-4c5e9759 e-flex e-con-boxed e-con e-child\" data-id=\"4c5e9759\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\r\n\t\t<div class=\"default no-position show_shadow rs-sticky-default elementor-element elementor-element-3021139d e-con-full e-flex e-con e-child\" data-id=\"3021139d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t\r\n\t\t<div class=\"default no-position show_shadow rs-sticky-default elementor-element elementor-element-44f6619f e-flex e-con-boxed e-con e-child\" data-id=\"44f6619f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\r\n\t\t\t\t<div class=\"elementor-element elementor-element-4b01edd6 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4b01edd6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\r\n\t\t<div class=\"default no-position show_shadow rs-sticky-default elementor-element elementor-element-4819b915 e-con-full e-flex e-con e-child\" data-id=\"4819b915\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\r\n\t\t<div class=\"default no-position show_shadow rs-sticky-default elementor-element elementor-element-34a95c35 e-flex e-con-boxed e-con e-child\" data-id=\"34a95c35\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\r\n\t\t\t\t<div class=\"elementor-element elementor-element-47a5e967 elementor-widget elementor-widget-rs-heading\" data-id=\"47a5e967\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"prelements-heading default  \">\n\t\t\t<div class=\"title-inner\">\n\t\t\t\t<h3 class=\"title rs-split-text-disable \">\u00bfTiene un proyecto en mente?<\/h3>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\r\n\t\t\t\t<div class=\"elementor-element elementor-element-4fee3706 elementor-widget elementor-widget-rs-button\" data-id=\"4fee3706\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"rs-button style1\">\r\n\t\t\t\t\t\t<a class=\"rs-btn\" href=\"https:\/\/euromotion.lu\/es\/contacto\/\" >\t\r\n\t\t\t\t<span>Cont\u00e1ctenos \r\n\t\t\t\t\t\t\t\t\t<em>\r\n\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"12\" viewBox=\"0 0 18 12\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M0 6C0 5.66249 0.273604 5.38889 0.611111 5.38889L15.0246 5.38889L11.179 1.54323C10.9403 1.30458 10.9403 0.917644 11.179 0.67899C11.4176 0.440336 11.8046 0.440336 12.0432 0.67899L16.9321 5.56788C17.1708 5.80653 17.1708 6.19347 16.9321 6.43212L12.0432 11.321C11.8046 11.5597 11.4176 11.5597 11.179 11.321C10.9403 11.0824 10.9403 10.6954 11.179 10.4568L15.0246 6.61111L0.611111 6.61111C0.273604 6.61111 0 6.33751 0 6Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"12\" viewBox=\"0 0 18 12\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M0 6C0 5.66249 0.273604 5.38889 0.611111 5.38889L15.0246 5.38889L11.179 1.54323C10.9403 1.30458 10.9403 0.917644 11.179 0.67899C11.4176 0.440336 11.8046 0.440336 12.0432 0.67899L16.9321 5.56788C17.1708 5.80653 17.1708 6.19347 16.9321 6.43212L12.0432 11.321C11.8046 11.5597 11.4176 11.5597 11.179 11.321C10.9403 11.0824 10.9403 10.6954 11.179 10.4568L15.0246 6.61111L0.611111 6.61111C0.273604 6.61111 0 6.33751 0 6Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t\t<\/em>\t\r\n\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t<\/a>\r\n\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Acoplamiento (cople) flexible Acoplamiento (cople) r\u00edgido Acoplamiento (cople) hidr\u00e1ulico Acoplamiento de engranes Campana de acoplamiento Reductor de velocidad Freno de contravuelta Freno neum\u00e1tico Freno hidr\u00e1ulico Freno de disco electromagn\u00e9tico Reductor de velocidad Conjunto de retenci\u00f3n Llantas libres Limitadores de torque Nuestros Productos Bearings Lubricating Grease Bearing Housings Linear Motion Systems and Components Power Transmission Components&#8230;<\/p>\n","protected":false},"author":1,"featured_media":29208,"parent":34731,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-34719","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Componentes de transmisi\u00f3n de potencia para aplicaciones industriales | EuromotionPower Transmission Components for Industrial Applications | Euromotion<\/title>\n<meta name=\"description\" content=\"Descubra componentes de transmisi\u00f3n de potencia de alta calidad, como acoplamientos, cajas de cambios y sistemas de transmisi\u00f3n, para aplicaciones industriales exigentes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/euromotion.lu\/es\/productos\/componentes-para-transmision-de-potencia-mecanica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Componentes de transmisi\u00f3n de potencia para aplicaciones industriales | EuromotionPower Transmission Components for Industrial Applications | Euromotion\" \/>\n<meta property=\"og:description\" content=\"Descubra componentes de transmisi\u00f3n de potencia de alta calidad, como acoplamientos, cajas de cambios y sistemas de transmisi\u00f3n, para aplicaciones industriales exigentes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/euromotion.lu\/es\/productos\/componentes-para-transmision-de-potencia-mecanica\/\" \/>\n<meta property=\"og:site_name\" content=\"EUROMOTION\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-16T13:22:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/euromotion.lu\/wp-content\/uploads\/2025\/03\/Power-Transmission-Components-e1741588042789.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1245\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/euromotion.lu\\\/es\\\/productos\\\/componentes-para-transmision-de-potencia-mecanica\\\/\",\"url\":\"https:\\\/\\\/euromotion.lu\\\/es\\\/productos\\\/componentes-para-transmision-de-potencia-mecanica\\\/\",\"name\":\"Componentes de transmisi\u00f3n de potencia para aplicaciones industriales | EuromotionPower Transmission Components for Industrial Applications | Euromotion\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/euromotion.lu\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/euromotion.lu\\\/es\\\/productos\\\/componentes-para-transmision-de-potencia-mecanica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/euromotion.lu\\\/es\\\/productos\\\/componentes-para-transmision-de-potencia-mecanica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/euromotion.lu\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Power-Transmission-Components-e1741588042789.jpeg\",\"datePublished\":\"2025-03-15T17:56:24+00:00\",\"dateModified\":\"2026-04-16T13:22:20+00:00\",\"description\":\"Descubra componentes de transmisi\u00f3n de potencia de alta calidad, como acoplamientos, cajas de cambios y sistemas de transmisi\u00f3n, para aplicaciones industriales exigentes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/euromotion.lu\\\/es\\\/productos\\\/componentes-para-transmision-de-potencia-mecanica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/euromotion.lu\\\/es\\\/productos\\\/componentes-para-transmision-de-potencia-mecanica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/euromotion.lu\\\/es\\\/productos\\\/componentes-para-transmision-de-potencia-mecanica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/euromotion.lu\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Power-Transmission-Components-e1741588042789.jpeg\",\"contentUrl\":\"https:\\\/\\\/euromotion.lu\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Power-Transmission-Components-e1741588042789.jpeg\",\"width\":1920,\"height\":1245,\"caption\":\"Motor coupling for reduce vibration and smooth start running, Connect the flexible shaft to an available spare motor for grinding and polishing work.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/euromotion.lu\\\/es\\\/productos\\\/componentes-para-transmision-de-potencia-mecanica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/euromotion.lu\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\\\/\\\/euromotion.lu\\\/es\\\/productos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Componentes para Transmisi\u00f3n de Potencia Mec\u00e1nica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/euromotion.lu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/euromotion.lu\\\/es\\\/\",\"name\":\"Euromotion SARL\",\"description\":\"Industrial Motion &amp; Power Transmission Solutions\",\"publisher\":{\"@id\":\"https:\\\/\\\/euromotion.lu\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/euromotion.lu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/euromotion.lu\\\/es\\\/#organization\",\"name\":\"Euromotion SARL\",\"url\":\"https:\\\/\\\/euromotion.lu\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/euromotion.lu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/euromotion.lu\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Euromotion-Logo.png\",\"contentUrl\":\"https:\\\/\\\/euromotion.lu\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Euromotion-Logo.png\",\"width\":1859,\"height\":365,\"caption\":\"Euromotion SARL\"},\"image\":{\"@id\":\"https:\\\/\\\/euromotion.lu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Componentes de transmisi\u00f3n de potencia para aplicaciones industriales | EuromotionPower Transmission Components for Industrial Applications | Euromotion","description":"Descubra componentes de transmisi\u00f3n de potencia de alta calidad, como acoplamientos, cajas de cambios y sistemas de transmisi\u00f3n, para aplicaciones industriales exigentes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/euromotion.lu\/es\/productos\/componentes-para-transmision-de-potencia-mecanica\/","og_locale":"es_ES","og_type":"article","og_title":"Componentes de transmisi\u00f3n de potencia para aplicaciones industriales | EuromotionPower Transmission Components for Industrial Applications | Euromotion","og_description":"Descubra componentes de transmisi\u00f3n de potencia de alta calidad, como acoplamientos, cajas de cambios y sistemas de transmisi\u00f3n, para aplicaciones industriales exigentes.","og_url":"https:\/\/euromotion.lu\/es\/productos\/componentes-para-transmision-de-potencia-mecanica\/","og_site_name":"EUROMOTION","article_modified_time":"2026-04-16T13:22:20+00:00","og_image":[{"width":1920,"height":1245,"url":"https:\/\/euromotion.lu\/wp-content\/uploads\/2025\/03\/Power-Transmission-Components-e1741588042789.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/euromotion.lu\/es\/productos\/componentes-para-transmision-de-potencia-mecanica\/","url":"https:\/\/euromotion.lu\/es\/productos\/componentes-para-transmision-de-potencia-mecanica\/","name":"Componentes de transmisi\u00f3n de potencia para aplicaciones industriales | EuromotionPower Transmission Components for Industrial Applications | Euromotion","isPartOf":{"@id":"https:\/\/euromotion.lu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/euromotion.lu\/es\/productos\/componentes-para-transmision-de-potencia-mecanica\/#primaryimage"},"image":{"@id":"https:\/\/euromotion.lu\/es\/productos\/componentes-para-transmision-de-potencia-mecanica\/#primaryimage"},"thumbnailUrl":"https:\/\/euromotion.lu\/wp-content\/uploads\/2025\/03\/Power-Transmission-Components-e1741588042789.jpeg","datePublished":"2025-03-15T17:56:24+00:00","dateModified":"2026-04-16T13:22:20+00:00","description":"Descubra componentes de transmisi\u00f3n de potencia de alta calidad, como acoplamientos, cajas de cambios y sistemas de transmisi\u00f3n, para aplicaciones industriales exigentes.","breadcrumb":{"@id":"https:\/\/euromotion.lu\/es\/productos\/componentes-para-transmision-de-potencia-mecanica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/euromotion.lu\/es\/productos\/componentes-para-transmision-de-potencia-mecanica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/euromotion.lu\/es\/productos\/componentes-para-transmision-de-potencia-mecanica\/#primaryimage","url":"https:\/\/euromotion.lu\/wp-content\/uploads\/2025\/03\/Power-Transmission-Components-e1741588042789.jpeg","contentUrl":"https:\/\/euromotion.lu\/wp-content\/uploads\/2025\/03\/Power-Transmission-Components-e1741588042789.jpeg","width":1920,"height":1245,"caption":"Motor coupling for reduce vibration and smooth start running, Connect the flexible shaft to an available spare motor for grinding and polishing work."},{"@type":"BreadcrumbList","@id":"https:\/\/euromotion.lu\/es\/productos\/componentes-para-transmision-de-potencia-mecanica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/euromotion.lu\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/euromotion.lu\/es\/productos\/"},{"@type":"ListItem","position":3,"name":"Componentes para Transmisi\u00f3n de Potencia Mec\u00e1nica"}]},{"@type":"WebSite","@id":"https:\/\/euromotion.lu\/es\/#website","url":"https:\/\/euromotion.lu\/es\/","name":"Euromotion SARL","description":"Industrial Motion &amp; Power Transmission Solutions","publisher":{"@id":"https:\/\/euromotion.lu\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/euromotion.lu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/euromotion.lu\/es\/#organization","name":"Euromotion SARL","url":"https:\/\/euromotion.lu\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/euromotion.lu\/es\/#\/schema\/logo\/image\/","url":"https:\/\/euromotion.lu\/wp-content\/uploads\/2025\/02\/Euromotion-Logo.png","contentUrl":"https:\/\/euromotion.lu\/wp-content\/uploads\/2025\/02\/Euromotion-Logo.png","width":1859,"height":365,"caption":"Euromotion SARL"},"image":{"@id":"https:\/\/euromotion.lu\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/euromotion.lu\/es\/wp-json\/wp\/v2\/pages\/34719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/euromotion.lu\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/euromotion.lu\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/euromotion.lu\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/euromotion.lu\/es\/wp-json\/wp\/v2\/comments?post=34719"}],"version-history":[{"count":2,"href":"https:\/\/euromotion.lu\/es\/wp-json\/wp\/v2\/pages\/34719\/revisions"}],"predecessor-version":[{"id":34736,"href":"https:\/\/euromotion.lu\/es\/wp-json\/wp\/v2\/pages\/34719\/revisions\/34736"}],"up":[{"embeddable":true,"href":"https:\/\/euromotion.lu\/es\/wp-json\/wp\/v2\/pages\/34731"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/euromotion.lu\/es\/wp-json\/wp\/v2\/media\/29208"}],"wp:attachment":[{"href":"https:\/\/euromotion.lu\/es\/wp-json\/wp\/v2\/media?parent=34719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}